{"id":7622,"date":"2022-11-23T16:01:40","date_gmt":"2022-11-23T09:01:40","guid":{"rendered":"https:\/\/www.ndrubber.co.th\/?p=7622"},"modified":"2026-05-08T09:23:30","modified_gmt":"2026-05-08T02:23:30","slug":"ndr-a651123","status":"publish","type":"post","link":"https:\/\/www.ndrubber.co.th\/en\/ndr-a651123\/","title":{"rendered":"\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19"},"content":{"rendered":"<p>\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e41\u0e1a\u0e1a \u0e22\u0e32\u0e07 TL \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48<br \/>\n\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e22\u0e32\u0e07\u0e41\u0e1a\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e27\u0e48\u0e32\u0e22\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e16\u0e36\u0e07\u0e40\u0e27\u0e25\u0e32\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07 \u0e43\u0e2b\u0e49\u0e14\u0e39\u0e08\u0e32\u0e01<\/p>\n<p>1. \u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e07 \u0e2b\u0e32\u0e01\u0e14\u0e2d\u0e01\u0e22\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e25\u0e49\u0e2d\u0e2a\u0e36\u0e01\u0e16\u0e36\u0e07\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e07 \u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e40\u0e27\u0e25\u0e32\u0e16\u0e19\u0e19\u0e40\u0e1b\u0e35\u0e22\u0e01<br \/>\n2. \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e22\u0e32\u0e07\u0e25\u0e49\u0e2d\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22<br \/>\n3. \u0e1c\u0e49\u0e32\u0e43\u0e1a\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e17\u0e34\u0e48\u0e21\u0e15\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e22\u0e32\u0e27<br \/>\n4. \u0e2b\u0e19\u0e49\u0e32\u0e22\u0e32\u0e07\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e09\u0e35\u0e01\u0e02\u0e32\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1c\u0e25\u0e43\u0e2b\u0e0d\u0e48<br \/>\n5. \u0e41\u0e01\u0e49\u0e21\u0e22\u0e32\u0e07\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e1b\u0e23\u0e34\u0e41\u0e15\u0e01 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e41\u0e15\u0e01\u0e25\u0e32\u0e22\u0e07\u0e32<\/p>\n<p>\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e22\u0e32\u0e07\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e41\u0e1a\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e16\u0e49\u0e32\u0e2b\u0e32\u0e01\u0e27\u0e48\u0e32\u0e21\u0e35\u0e08\u0e38\u0e14\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e40\u0e02\u0e49\u0e32\u0e02\u0e48\u0e32\u0e22\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e01\u0e25\u0e48\u0e32\u0e27\u0e44\u0e27\u0e49\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e35\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e17\u0e31\u0e19\u0e17\u0e35<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e41\u0e1a\u0e1a \u0e22\u0e32\u0e07 TL \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e22\u0e32\u0e07\u0e41\u0e1a\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e27\u0e48\u0e32\u0e22\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e16\u0e36\u0e07\u0e40\u0e27\u0e25\u0e32\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07 \u0e43\u0e2b\u0e49\u0e14\u0e39\u0e08\u0e32\u0e01 1. \u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e07 \u0e2b\u0e32\u0e01\u0e14\u0e2d\u0e01\u0e22\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e25\u0e49\u0e2d\u0e2a\u0e36\u0e01\u0e16\u0e36\u0e07\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e07 \u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e40\u0e27\u0e25\u0e32\u0e16\u0e19\u0e19\u0e40\u0e1b\u0e35\u0e22\u0e01 2. \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e22\u0e32\u0e07\u0e25\u0e49\u0e2d\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22 3. \u0e1c\u0e49\u0e32\u0e43\u0e1a\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e17\u0e34\u0e48\u0e21\u0e15\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e22\u0e32\u0e27 4. \u0e2b\u0e19\u0e49\u0e32\u0e22\u0e32\u0e07\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e09\u0e35\u0e01\u0e02\u0e32\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1c\u0e25\u0e43\u0e2b\u0e0d\u0e48 5. \u0e41\u0e01\u0e49\u0e21\u0e22\u0e32\u0e07\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e1b\u0e23\u0e34\u0e41\u0e15\u0e01 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e41\u0e15\u0e01\u0e25\u0e32\u0e22\u0e07\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e22\u0e32\u0e07\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e41\u0e1a\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e16\u0e49\u0e32\u0e2b\u0e32\u0e01\u0e27\u0e48\u0e32\u0e21\u0e35\u0e08\u0e38\u0e14\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e40\u0e02\u0e49\u0e32\u0e02\u0e48\u0e32\u0e22\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e01\u0e25\u0e48\u0e32\u0e27\u0e44\u0e27\u0e49\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e35\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e17\u0e31\u0e19\u0e17\u0e35 &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":10972,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19<\/title>\n<meta name=\"description\" content=\"\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e41\u0e1a\u0e1a \u0e22\u0e32\u0e07 TL \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ndrubber.co.th\/en\/ndr-a651123\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19\" \/>\n<meta property=\"og:description\" content=\"\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e41\u0e1a\u0e1a \u0e22\u0e32\u0e07 TL \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/\" \/>\n<meta property=\"og:site_name\" content=\"ND Rubber\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-23T09:01:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T02:23:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2022\/11\/\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15-\u0e22\u0e32\u0e07-TL-\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1717\" \/>\n\t<meta property=\"og:image:height\" content=\"916\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"bemyfriend\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"bemyfriend\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/\"},\"author\":{\"name\":\"bemyfriend\",\"@id\":\"https:\/\/www.ndrubber.co.th\/#\/schema\/person\/22d9e0df0679d1ecf0230a5af99b3b68\"},\"headline\":\"\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19\",\"datePublished\":\"2022-11-23T09:01:40+00:00\",\"dateModified\":\"2026-05-08T02:23:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/\"},\"wordCount\":3,\"publisher\":{\"@id\":\"https:\/\/www.ndrubber.co.th\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2022\/11\/\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15-\u0e22\u0e32\u0e07-TL-\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19.png\",\"articleSection\":[\"Tire Knowledge\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/\",\"url\":\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/\",\"name\":\"\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19\",\"isPartOf\":{\"@id\":\"https:\/\/www.ndrubber.co.th\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2022\/11\/\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15-\u0e22\u0e32\u0e07-TL-\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19.png\",\"datePublished\":\"2022-11-23T09:01:40+00:00\",\"dateModified\":\"2026-05-08T02:23:30+00:00\",\"description\":\"\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e41\u0e1a\u0e1a \u0e22\u0e32\u0e07 TL \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#primaryimage\",\"url\":\"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2022\/11\/\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15-\u0e22\u0e32\u0e07-TL-\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19.png\",\"contentUrl\":\"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2022\/11\/\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15-\u0e22\u0e32\u0e07-TL-\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19.png\",\"width\":1717,\"height\":916,\"caption\":\"\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ndrubber.co.th\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ndrubber.co.th\/#website\",\"url\":\"https:\/\/www.ndrubber.co.th\/\",\"name\":\"ND Rubber\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ndrubber.co.th\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ndrubber.co.th\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ndrubber.co.th\/#organization\",\"name\":\"ND Rubber\",\"url\":\"https:\/\/www.ndrubber.co.th\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.ndrubber.co.th\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2025\/11\/cropped-cropped-LOGO-ND-RUBBER-SLOGAN.png\",\"contentUrl\":\"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2025\/11\/cropped-cropped-LOGO-ND-RUBBER-SLOGAN.png\",\"width\":1006,\"height\":585,\"caption\":\"ND Rubber\"},\"image\":{\"@id\":\"https:\/\/www.ndrubber.co.th\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ndrubber.co.th\/#\/schema\/person\/22d9e0df0679d1ecf0230a5af99b3b68\",\"name\":\"bemyfriend\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.ndrubber.co.th\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c0bb26f114863231f834243189c3ed1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c0bb26f114863231f834243189c3ed1d?s=96&d=mm&r=g\",\"caption\":\"bemyfriend\"},\"sameAs\":[\"https:\/\/www.ndrubber.co.th\"],\"url\":\"https:\/\/www.ndrubber.co.th\/en\/author\/bemyfriend\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19","description":"\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e41\u0e1a\u0e1a \u0e22\u0e32\u0e07 TL \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ndrubber.co.th\/en\/ndr-a651123\/","og_locale":"en_US","og_type":"article","og_title":"\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19","og_description":"\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e41\u0e1a\u0e1a \u0e22\u0e32\u0e07 TL \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21","og_url":"https:\/\/www.ndrubber.co.th\/ndr-a651123\/","og_site_name":"ND Rubber","article_published_time":"2022-11-23T09:01:40+00:00","article_modified_time":"2026-05-08T02:23:30+00:00","og_image":[{"width":1717,"height":916,"url":"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2022\/11\/\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15-\u0e22\u0e32\u0e07-TL-\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19.png","type":"image\/png"}],"author":"bemyfriend","twitter_card":"summary_large_image","twitter_misc":{"Written by":"bemyfriend","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#article","isPartOf":{"@id":"https:\/\/www.ndrubber.co.th\/ndr-a651123\/"},"author":{"name":"bemyfriend","@id":"https:\/\/www.ndrubber.co.th\/#\/schema\/person\/22d9e0df0679d1ecf0230a5af99b3b68"},"headline":"\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19","datePublished":"2022-11-23T09:01:40+00:00","dateModified":"2026-05-08T02:23:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ndrubber.co.th\/ndr-a651123\/"},"wordCount":3,"publisher":{"@id":"https:\/\/www.ndrubber.co.th\/#organization"},"image":{"@id":"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2022\/11\/\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15-\u0e22\u0e32\u0e07-TL-\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19.png","articleSection":["Tire Knowledge"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ndrubber.co.th\/ndr-a651123\/","url":"https:\/\/www.ndrubber.co.th\/ndr-a651123\/","name":"\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19","isPartOf":{"@id":"https:\/\/www.ndrubber.co.th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#primaryimage"},"image":{"@id":"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2022\/11\/\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15-\u0e22\u0e32\u0e07-TL-\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19.png","datePublished":"2022-11-23T09:01:40+00:00","dateModified":"2026-05-08T02:23:30+00:00","description":"\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e41\u0e1a\u0e1a \u0e22\u0e32\u0e07 TL \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21","breadcrumb":{"@id":"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ndrubber.co.th\/ndr-a651123\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#primaryimage","url":"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2022\/11\/\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15-\u0e22\u0e32\u0e07-TL-\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19.png","contentUrl":"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2022\/11\/\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15-\u0e22\u0e32\u0e07-TL-\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19.png","width":1717,"height":916,"caption":"\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ndrubber.co.th\/ndr-a651123\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ndrubber.co.th\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e22\u0e32\u0e07 TL \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19"}]},{"@type":"WebSite","@id":"https:\/\/www.ndrubber.co.th\/#website","url":"https:\/\/www.ndrubber.co.th\/","name":"ND Rubber","description":"","publisher":{"@id":"https:\/\/www.ndrubber.co.th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ndrubber.co.th\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ndrubber.co.th\/#organization","name":"ND Rubber","url":"https:\/\/www.ndrubber.co.th\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ndrubber.co.th\/#\/schema\/logo\/image\/","url":"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2025\/11\/cropped-cropped-LOGO-ND-RUBBER-SLOGAN.png","contentUrl":"https:\/\/www.ndrubber.co.th\/wp-content\/uploads\/2025\/11\/cropped-cropped-LOGO-ND-RUBBER-SLOGAN.png","width":1006,"height":585,"caption":"ND Rubber"},"image":{"@id":"https:\/\/www.ndrubber.co.th\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ndrubber.co.th\/#\/schema\/person\/22d9e0df0679d1ecf0230a5af99b3b68","name":"bemyfriend","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ndrubber.co.th\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c0bb26f114863231f834243189c3ed1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0bb26f114863231f834243189c3ed1d?s=96&d=mm&r=g","caption":"bemyfriend"},"sameAs":["https:\/\/www.ndrubber.co.th"],"url":"https:\/\/www.ndrubber.co.th\/en\/author\/bemyfriend\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ndrubber.co.th\/en\/wp-json\/wp\/v2\/posts\/7622"}],"collection":[{"href":"https:\/\/www.ndrubber.co.th\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ndrubber.co.th\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ndrubber.co.th\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ndrubber.co.th\/en\/wp-json\/wp\/v2\/comments?post=7622"}],"version-history":[{"count":2,"href":"https:\/\/www.ndrubber.co.th\/en\/wp-json\/wp\/v2\/posts\/7622\/revisions"}],"predecessor-version":[{"id":10974,"href":"https:\/\/www.ndrubber.co.th\/en\/wp-json\/wp\/v2\/posts\/7622\/revisions\/10974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ndrubber.co.th\/en\/wp-json\/wp\/v2\/media\/10972"}],"wp:attachment":[{"href":"https:\/\/www.ndrubber.co.th\/en\/wp-json\/wp\/v2\/media?parent=7622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ndrubber.co.th\/en\/wp-json\/wp\/v2\/categories?post=7622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ndrubber.co.th\/en\/wp-json\/wp\/v2\/tags?post=7622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}